{"id":3434,"date":"2020-11-17T08:25:42","date_gmt":"2020-11-17T08:25:42","guid":{"rendered":"https:\/\/www.itasean.org\/?post_type=tribe_events&#038;p=3434"},"modified":"2021-02-16T09:46:44","modified_gmt":"2021-02-16T09:46:44","slug":"rcep-cosa-cambia-per-la-regione-dellindo-pacifico-e-per-il-sistema-italia","status":"publish","type":"tribe_events","link":"https:\/\/www.itasean.org\/en\/eventi\/rcep-cosa-cambia-per-la-regione-dellindo-pacifico-e-per-il-sistema-italia\/","title":{"rendered":"RCEP: cosa cambia per la regione dell&#8217;Indo-Pacifico e per il Sistema Italia"},"content":{"rendered":"<div class=\"tribe-events-schedule tribe-clearfix\">\n\t<h2 class=\"tribe-events-schedule__datetime\">\n\t\t<span class=\"tribe-events-schedule__date tribe-events-schedule__date--start\">\n\t\t\t24 November, 2020\t\t<\/span>\n\n\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--date\">\n\t\t\t\t &#8211; \t\t\t<\/span>\n\t\t\t<span class=\"tribe-events-schedule__time tribe-events-schedule__time--start\">\n\t\t\t\t12:00 pm\t\t\t<\/span>\n\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--time\">\n\t\t\t\t\t \t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"tribe-events-schedule__time tribe-events-schedule__time--end\">\n\t\t\t\t\t1:30 pm\t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t<\/h2>\n<\/div>\n\r\n<p>&nbsp;<\/p>\r\n\t<div class=\"tribe-block tribe-block__events-link\">\n\t\t\t\t\t<div class=\"tribe-block__btn--link tribe-block__events-gcal\">\n\t\t\t\t<a\n\t\t\t\t\thref=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&text=RCEP%3A+cosa+cambia+per+la+regione+dell%27Indo-Pacifico+e+per+il+Sistema+Italia&dates=20201124T120000\/20201124T133000&details=+%0A%26nbsp%3B+%0A%0A%0A%0A%0A%09%0A%09%09%0A%09%09%0A%09%09%09%0A%09%09%0A%09%0A%0A%09%0A%09%09%0A%09%09%09L%26%238217%3BAssociazione+Italia-ASEAN+organizza+una+tavola+rotonda+per+illustrare+cosa+cambier%C3%A0+per+la+regione+dell%26%238217%3BIndo-Pacifico+e+per+il+Sistema+Italia+alla+luce+della+nuova+Regional+Comprehensive+Economic+Partnership+%28RCEP%29%2C+firmata+il+15+novembre+2020+dai+Paesi+dell%26%238217%3BASEAN%2C+Australia%2C+Cina%2C+Corea+del+Sud%2C+Giappone%2C+Nuova+Zelanda.%0A+%0AIntervengono+%0A%0AEnrico+Letta%2C+Presidente%2C+Associazione+Italia-ASEAN%0A%0ADanilo+Taino%2C+Editorialista+Corriere+della+Sera%0A%0AGabriella+Biondi%2C+Direttrice+Asia-Pacifico+%26%238211%3B+MAECI%0A%0AStefano+Cao%2C+Amministratore+Delegato+Saipem%0A%0A%0A+%0AModera+%0A%0AAlessia+Mosca%2C+Segretario+Generale%2C+Associazione+Italia-ASEAN%0A%0A%26nbsp%3B+%0A%0A+%0A+%0AISCRIVITI+QUI%0A%0A%0A%09%09%0A%09%0A%0A%0A%0A%09%0A%09%09%0A%09%09%09%0A%09%09%0A%09%0A%0A+%0A%0AIscriviti+anche+alla+nostra+newsletter+per+non+perdere+nessuna+notizia%21+%0A%0A%0A%0ANome%0A%0ACognome%0AEmail%0A%0A%26nbsp%3BIscrizione+newsletter+sito+associazione+Italia-Asean%0A%26nbsp%3Blanding%0AArgomento%0AargomentoGeopolitcaSostenibilit%C3%A0EconomiaInnovazioneNotizie%0A%0A%26nbsp%3BProcedendo+ac+%28View+Full+Event+Description+Here%3A+https%3A%2F%2Fwww.itasean.org%2Fen%2Feventi%2Frcep-cosa-cambia-per-la-regione-dellindo-pacifico-e-per-il-sistema-italia%2F%29&location&trp=false&sprop=website:https:\/\/www.itasean.org\/en\/&ctz=UTC\"\n\t\t\t\t\ttitle=\"Add to Google Calendar\"\n\t\t\t\t>\n\t\t\t\t\t<img src=\"https:\/\/www.itasean.org\/wp-content\/plugins\/event-tickets\/common\/src\/modules\/icons\/link.svg\" \/>\n\t\t\t\t\tGoogle Calendar\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"tribe-block__btn--link tribe-block__-events-ical\">\n\t\t\t\t<a\n\t\t\t\t\thref=\"https:\/\/www.itasean.org\/en\/eventi\/rcep-cosa-cambia-per-la-regione-dellindo-pacifico-e-per-il-sistema-italia\/?ical=1\"\n\t\t\t\t\ttitle=\"Download .ics file\"\n\t\t\t\t>\n\t\t\t\t\t<img src=\"https:\/\/www.itasean.org\/wp-content\/plugins\/event-tickets\/common\/src\/modules\/icons\/link.svg\" \/>\n\t\t\t\t\tiCal Export\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\n\r\n<div class=\"container inner-relative-wrapper\"><div class=\"row section-theme-padding\"><div class=\"row-cols-wrap vc_row wpb_row vc_row-fluid\">\n\n<div class=\"wpb_column vc_column_container vc_col-sm-8\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img width=\"5490\" height=\"3072\" src=\"https:\/\/www.itasean.org\/wp-content\/uploads\/2020\/11\/rcep@2x-1.png\" class=\"vc_single_image-img attachment-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.itasean.org\/wp-content\/uploads\/2020\/11\/rcep@2x-1.png 5490w, https:\/\/www.itasean.org\/wp-content\/uploads\/2020\/11\/rcep@2x-1-300x168.png 300w, https:\/\/www.itasean.org\/wp-content\/uploads\/2020\/11\/rcep@2x-1-1024x573.png 1024w, https:\/\/www.itasean.org\/wp-content\/uploads\/2020\/11\/rcep@2x-1-768x430.png 768w, https:\/\/www.itasean.org\/wp-content\/uploads\/2020\/11\/rcep@2x-1-1536x859.png 1536w, https:\/\/www.itasean.org\/wp-content\/uploads\/2020\/11\/rcep@2x-1-2048x1146.png 2048w, https:\/\/www.itasean.org\/wp-content\/uploads\/2020\/11\/rcep@2x-1-600x336.png 600w, https:\/\/www.itasean.org\/wp-content\/uploads\/2020\/11\/rcep@2x-1-16x9.png 16w\" sizes=\"(max-width: 5490px) 100vw, 5490px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>L&#8217;Associazione Italia-ASEAN organizza una tavola rotonda per illustrare cosa cambier\u00e0 per la regione dell&#8217;Indo-Pacifico e per il Sistema Italia alla luce della nuova <b>Regional Comprehensive Economic Partnership<\/b> (<b>RCEP<\/b>), firmata il 15 novembre 2020 dai Paesi dell&#8217;ASEAN, Australia, Cina, Corea del Sud, Giappone, Nuova Zelanda.<\/p>\n<p><strong>Intervengono<\/strong><\/p>\n<ul>\n<li><em><em><strong>Enrico Letta<\/strong>, Presidente, Associazione Italia-ASEAN<br \/><\/em><\/em>\n<\/li>\n<li><em><em><strong>Danilo Taino<\/strong>, Editorialista Corriere della Sera<br \/><\/em><\/em>\n<\/li>\n<li><em><em><strong>Gabriella Biondi<\/strong>, Direttrice Asia-Pacifico &#8211; MAECI<br \/><\/em><\/em>\n<\/li>\n<li><em><em><strong>Stefano Cao<\/strong>, Amministratore Delegato Saipem<br \/><\/em><\/em>\n<\/li>\n<\/ul>\n<p><strong>Modera<\/strong><\/p>\n<ul>\n<li><em><em><strong>Alessia Mosca<\/strong>, Segretario Generale, Associazione Italia-ASEAN<br \/><\/em><\/em>\n<\/li>\n<p>&nbsp;<\/p>\n<div class=\"wp-block-buttons aligncenter\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-text-color has-very-light-gray-color has-background has-vivid-cyan-blue-background-color\" href=\"https:\/\/forms.gle\/dN4QukQsrz82ix1o7\">ISCRIVITI QUI<\/a><\/div>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"container inner-relative-wrapper\"><div class=\"row section-theme-padding\"><div class=\"row-cols-wrap vc_row wpb_row vc_row-fluid\">\n\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div>\n\t<\/div>\r\n<hr class=\"wp-block-separator has-text-color has-background has-vivid-cyan-blue-background-color has-vivid-cyan-blue-color is-style-wide\" \/>\r\n\r\n<div class=\"wp-block-tnp-minimal\" style=\"background-color: #2980b9; color: #ffffff; padding: 20px; text-align: center;\">\r\n<p><span class=\"has-inline-color has-very-light-gray-color\"><strong>Iscriviti anche alla nostra newsletter per non perdere nessuna notizia!<\/strong><\/span><\/p>\r\n<div><div class=\"tnp tnp-subscription\">\n<form method=\"post\" action=\"https:\/\/www.itasean.org\/en\/?na=s\">\n\n<input type=\"hidden\" name=\"nlang\" value=\"\"><div class=\"tnp-field tnp-field-firstname\"><label for=\"tnp-name\">Nome<\/label>\n<input class=\"tnp-name\" type=\"text\" name=\"nn\" value=\"\"><\/div>\n<div class=\"tnp-field tnp-field-surname\"><label for=\"tnp-surname\">Cognome<\/label>\n<input class=\"tnp-surname\" type=\"text\" name=\"ns\" value=\"\"><\/div><div class=\"tnp-field tnp-field-email\"><label for=\"tnp-email\">Email<\/label>\n<input class=\"tnp-email\" type=\"email\" name=\"ne\" value=\"\" required><\/div>\n<div class=\"tnp-field tnp-field-checkbox tnp-field-list\"><label for=\"nl1\"><input type=\"checkbox\" id=\"nl1\" name=\"nl[]\" value=\"1\">&nbsp;Iscrizione newsletter sito associazione Italia-Asean<\/label><\/div>\n<div class=\"tnp-field tnp-field-checkbox tnp-field-list\"><label for=\"nl16\"><input type=\"checkbox\" id=\"nl16\" name=\"nl[]\" value=\"16\">&nbsp;landing<\/label><\/div>\n<div class=\"tnp-field tnp-field-profile\"><label for=\"tnp-profile_14\">Argomento<\/label>\n<select class=\"tnp-profile tnp-profile-14\" id=\"tnp-profile_14\" name=\"np14\" required><option value=\"\" selected disabled>argomento<\/option><option>Geopolitca<\/option><option>Sostenibilit\u00e0<\/option><option>Economia<\/option><option>Innovazione<\/option><option>Notizie<\/option><\/select>\n<\/div>\n<div class=\"tnp-field tnp-privacy-field\"><label><input type=\"checkbox\" name=\"ny\" required class=\"tnp-privacy\">&nbsp;Procedendo accetti la privacy policy<\/label><\/div><div class=\"tnp-field tnp-field-button\"><input class=\"tnp-submit\" type=\"submit\" value=\"Iscriviti\" style=\"background-color:#FFFFFF\">\n<\/div>\n<\/form>\n<\/div>\n<\/div>\r\n<\/div>\r\n\r\n<div class=\"tribe-block tribe-block__event-price\">\n\t\t<\/div>\n\r\n\r\n<div class=\"tribe-block tribe-block__venue tribe-block__venue--has-map\">\n\t\n\t\t\n\t<\/div>\n\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n\u00a0\r\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Iscriviti anche alla nostra newsletter per non perdere nessuna notizia! &nbsp; \u00a0<\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":[],"_tribe_ticket_has_attendee_info_fields":false,"_EventAllDay":false,"_EventTimezone":"UTC","_EventStartDate":"2020-11-24 12:00:00","_EventEndDate":"2020-11-24 13:30:00","_EventStartDateUTC":"2020-11-24 12:00:00","_EventEndDateUTC":"2020-11-24 13:30:00","_EventShowMap":true,"_EventShowMapLink":true,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"\u20ac","_EventCurrencyPosition":"prefix","_EventDateTimeSeparator":" - ","_EventTimeRangeSeparator":" ","_EventOrganizerID":[],"_EventVenueID":0,"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":""},"tags":[105,236,406,146,195],"tribe_events_cat":[87],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>RCEP: cosa cambia per la regione dell&#039;Indo-Pacifico e per il Sistema Italia - Associazione Italia Asean<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itasean.org\/en\/eventi\/rcep-cosa-cambia-per-la-regione-dellindo-pacifico-e-per-il-sistema-italia\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RCEP: cosa cambia per la regione dell&#039;Indo-Pacifico e per il Sistema Italia - Associazione Italia Asean\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Iscriviti anche alla nostra newsletter per non perdere nessuna notizia! &nbsp; \u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itasean.org\/en\/eventi\/rcep-cosa-cambia-per-la-regione-dellindo-pacifico-e-per-il-sistema-italia\/\" \/>\n<meta property=\"og:site_name\" content=\"Associazione Italia Asean\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-16T09:46:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.itasean.org\/#website\",\"url\":\"https:\/\/www.itasean.org\/\",\"name\":\"Associazione Italia Asean\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.itasean.org\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.itasean.org\/eventi\/rcep-cosa-cambia-per-la-regione-dellindo-pacifico-e-per-il-sistema-italia\/#webpage\",\"url\":\"https:\/\/www.itasean.org\/eventi\/rcep-cosa-cambia-per-la-regione-dellindo-pacifico-e-per-il-sistema-italia\/\",\"name\":\"RCEP: cosa cambia per la regione dell'Indo-Pacifico e per il Sistema Italia - Associazione Italia Asean\",\"isPartOf\":{\"@id\":\"https:\/\/www.itasean.org\/#website\"},\"datePublished\":\"2020-11-17T08:25:42+00:00\",\"dateModified\":\"2021-02-16T09:46:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.itasean.org\/eventi\/rcep-cosa-cambia-per-la-regione-dellindo-pacifico-e-per-il-sistema-italia\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.itasean.org\/eventi\/rcep-cosa-cambia-per-la-regione-dellindo-pacifico-e-per-il-sistema-italia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.itasean.org\/eventi\/rcep-cosa-cambia-per-la-regione-dellindo-pacifico-e-per-il-sistema-italia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.itasean.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventi\",\"item\":\"https:\/\/www.itasean.org\/eventi\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"RCEP: cosa cambia per la regione dell&#8217;Indo-Pacifico e per il Sistema Italia\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RCEP: cosa cambia per la regione dell'Indo-Pacifico e per il Sistema Italia - Associazione Italia Asean","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itasean.org\/en\/eventi\/rcep-cosa-cambia-per-la-regione-dellindo-pacifico-e-per-il-sistema-italia\/","og_locale":"en_GB","og_type":"article","og_title":"RCEP: cosa cambia per la regione dell'Indo-Pacifico e per il Sistema Italia - Associazione Italia Asean","og_description":"&nbsp; Iscriviti anche alla nostra newsletter per non perdere nessuna notizia! &nbsp; \u00a0","og_url":"https:\/\/www.itasean.org\/en\/eventi\/rcep-cosa-cambia-per-la-regione-dellindo-pacifico-e-per-il-sistema-italia\/","og_site_name":"Associazione Italia Asean","article_modified_time":"2021-02-16T09:46:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.itasean.org\/#website","url":"https:\/\/www.itasean.org\/","name":"Associazione Italia Asean","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itasean.org\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.itasean.org\/eventi\/rcep-cosa-cambia-per-la-regione-dellindo-pacifico-e-per-il-sistema-italia\/#webpage","url":"https:\/\/www.itasean.org\/eventi\/rcep-cosa-cambia-per-la-regione-dellindo-pacifico-e-per-il-sistema-italia\/","name":"RCEP: cosa cambia per la regione dell'Indo-Pacifico e per il Sistema Italia - Associazione Italia Asean","isPartOf":{"@id":"https:\/\/www.itasean.org\/#website"},"datePublished":"2020-11-17T08:25:42+00:00","dateModified":"2021-02-16T09:46:44+00:00","breadcrumb":{"@id":"https:\/\/www.itasean.org\/eventi\/rcep-cosa-cambia-per-la-regione-dellindo-pacifico-e-per-il-sistema-italia\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itasean.org\/eventi\/rcep-cosa-cambia-per-la-regione-dellindo-pacifico-e-per-il-sistema-italia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.itasean.org\/eventi\/rcep-cosa-cambia-per-la-regione-dellindo-pacifico-e-per-il-sistema-italia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.itasean.org\/"},{"@type":"ListItem","position":2,"name":"Eventi","item":"https:\/\/www.itasean.org\/eventi\/"},{"@type":"ListItem","position":3,"name":"RCEP: cosa cambia per la regione dell&#8217;Indo-Pacifico e per il Sistema Italia"}]}]}},"_links":{"self":[{"href":"https:\/\/www.itasean.org\/en\/wp-json\/wp\/v2\/tribe_events\/3434"}],"collection":[{"href":"https:\/\/www.itasean.org\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.itasean.org\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.itasean.org\/en\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itasean.org\/en\/wp-json\/wp\/v2\/comments?post=3434"}],"version-history":[{"count":15,"href":"https:\/\/www.itasean.org\/en\/wp-json\/wp\/v2\/tribe_events\/3434\/revisions"}],"predecessor-version":[{"id":3479,"href":"https:\/\/www.itasean.org\/en\/wp-json\/wp\/v2\/tribe_events\/3434\/revisions\/3479"}],"wp:attachment":[{"href":"https:\/\/www.itasean.org\/en\/wp-json\/wp\/v2\/media?parent=3434"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itasean.org\/en\/wp-json\/wp\/v2\/tags?post=3434"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.itasean.org\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=3434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}